{"id":1223,"date":"2020-04-03T16:08:40","date_gmt":"2020-04-03T14:08:40","guid":{"rendered":"https:\/\/www.oltresrl.eu\/?page_id=1223"},"modified":"2020-10-01T15:25:44","modified_gmt":"2020-10-01T13:25:44","slug":"tecnico-di-segreteria-amministrativa-focus-pacchetto-office","status":"publish","type":"page","link":"https:\/\/www.oltresrl.eu\/index.php\/tecnico-di-segreteria-amministrativa-focus-pacchetto-office\/","title":{"rendered":"Tecnico Di Segreteria Amministrativa &#8211; Focus Pacchetto Office"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1223\" class=\"elementor elementor-1223\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a573a7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a573a7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-013b261\" data-id=\"013b261\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3764232 elementor-widget elementor-widget-heading\" data-id=\"3764232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tecnico Di Segreteria Amministrativa - Focus Pacchetto Office<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12a858d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12a858d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6dfcc6\" data-id=\"c6dfcc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5a6f2e elementor-widget elementor-widget-spacer\" data-id=\"a5a6f2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7ad518 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7ad518\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a8406c8\" data-id=\"a8406c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e36039 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"3e36039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/www.oltresrl.eu\/wp-content\/uploads\/2020\/04\/16.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-1162\" alt=\"\" srcset=\"https:\/\/www.oltresrl.eu\/wp-content\/uploads\/2020\/04\/16.png 940w, https:\/\/www.oltresrl.eu\/wp-content\/uploads\/2020\/04\/16-600x503.png 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34eda3c\" data-id=\"34eda3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85e3352 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"85e3352\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Sbocchi lavorativi<\/h2><div class=\"aux-modern-heading-divider\"><\/div><div class=\"aux-modern-heading-description\"><p>Il tecnico di segretaria amministrativa pu\u00f2 lavorare:<\/p><p>- in un\u2019azienda nel settore contabilit\u00e0 e finanza con il ruolo di responsabile coordinamento e programmazione della segreteria amministrativa;<\/p><p>- in studi privati come quelli medici o legali con il ruolo di assistenza clienti, front-office o receptionist;<\/p><p>- in aziende con il ruolo di segretario di direzione a cui pu\u00f2 essere affidato il ruolo di Executive Assistant per manager di livello alto.<\/p><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52391eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52391eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da8e492\" data-id=\"da8e492\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44d9ad9 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"44d9ad9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Informazioni sul corso<\/h2><div class=\"aux-modern-heading-divider\"><\/div><div class=\"aux-modern-heading-description\"><p>Il corso \u00e8 rivolto a coloro che intendono acquisire conoscenze e competenze specifiche in merito al profilo professionale Tecnico di Segreteria Amministrativa (focus Pacchetto Office), sviluppando competenze tecniche, organizzative e relazionali per gestire l\u2019amministrazione in sinergia con le altre funzioni aziendali.<\/p><p>Durante il percorso verranno utilizzati strumenti per la gestione dei flussi informativi in entrata ed in uscita e per la rielaborazione dei contenuti della comunicazione aziendale tramite i programmi pi\u00f9 utili del pacchetto Office. Infatti il focus del corso verte proprio sull'utilizzo degli strumenti Office per la gestione aziendale, con un ampio dettaglio sull'utilizzo di Excel in ambito amministrativo. Tale figura professionale \u00e8 in grado di tradurre verso l\u2019esterno messaggi in linea con la vision e la mission aziendale, avvalendosi di strumenti informatici e telematici. In azienda, il Tecnico di Segreteria Amministrativa (focus Pacchetto Office) pu\u00f2 offrire un valido supporto a tutte le aree aziendali contribuendo in modo efficace anche alla creazione, presentazione, rielaborazione di documenti in linea con le nuove normative privacy per il corretto trattamento dei dati personali.<\/p><p>A fine corso i partecipanti saranno in grado di gestire, organizzare e pianificare le attivit\u00e0 inerenti alla segreteria amministrativa, utilizzare gli strumenti del pacchetto Office, in particolare Excel per la gestione delle attivit\u00e0 amministrative, operando attraverso una buona comunicazione aziendale ed interpersonale.<\/p><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58a84b8\" data-id=\"58a84b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f15fb1d elementor-widget elementor-widget-aux_modern_heading\" data-id=\"f15fb1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">Moduli Formativi<\/h2><div class=\"aux-modern-heading-divider\"><\/div><div class=\"aux-modern-heading-description\"><p>- COMUNICAZIONE EFFICACE: STRUMENTI WEB E SOCIAL<\/p><p>- LAVORARE IN TEAM<\/p><p>- ORGANIZZAZIONE AZIENDALE<\/p><p>- STRUMENTI E TECNICHE DI SEGRETERIA<\/p><p>- STRUMENTI INFORMATICI PER LA SEGRETERIA: il pacchetto office<\/p><p>- GLI UTILIZZI DI EXCEL NELLA GESTIONE AZIENDALE<\/p><p>- TECNICHE DI AMMINISTRAZIONE CONTABILE<\/p><p>- LINGUA INGLESE PER LA SEGRETERIA<\/p><p>- LA GESTIONE DELLA PRIVACY IN AZIENDA<\/p><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07c2b50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07c2b50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc815bb\" data-id=\"bc815bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2eee41 elementor-widget elementor-widget-html\" data-id=\"b2eee41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<center>[wpforms id=\"2650\"]<\/center>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tecnico Di Segreteria Amministrativa &#8211; Focus Pacchetto Office Sbocchi lavorativi Il tecnico di segretaria amministrativa pu\u00f2 lavorare: &#8211; in un\u2019azienda nel settore contabilit\u00e0 e finanza con il ruolo di responsabile coordinamento e programmazione della segreteria amministrativa; &#8211; in studi privati come quelli medici o legali con il ruolo di assistenza clienti, front-office o receptionist; &#8211; [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1223","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/pages\/1223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/comments?post=1223"}],"version-history":[{"count":4,"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/pages\/1223\/revisions"}],"predecessor-version":[{"id":2978,"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/pages\/1223\/revisions\/2978"}],"wp:attachment":[{"href":"https:\/\/www.oltresrl.eu\/index.php\/wp-json\/wp\/v2\/media?parent=1223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}